{"id":25597,"date":"2024-10-29T20:11:12","date_gmt":"2024-10-29T19:11:12","guid":{"rendered":"https:\/\/grupochile.de\/?p=25597"},"modified":"2025-03-30T21:26:23","modified_gmt":"2025-03-30T19:26:23","slug":"angela-carrillo-y-claudio-rivera-campeones-mundiales-de-cueca-en-cofochilex-2024","status":"publish","type":"post","link":"https:\/\/grupochile.de\/de\/angela-carrillo-y-claudio-rivera-campeones-mundiales-de-cueca-en-cofochilex-2024\/","title":{"rendered":"Angela Carrillo und Claudio Rivera: Weltmeister der Cueca bei COFOCHILEX 2024"},"content":{"rendered":"<style>.wp-block-kadence-advancedheading.kt-adv-heading25597_02146f-46, .wp-block-kadence-advancedheading.kt-adv-heading25597_02146f-46[data-kb-block=\"kb-adv-heading25597_02146f-46\"]{font-size:25px;line-height:1;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading25597_02146f-46 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading25597_02146f-46[data-kb-block=\"kb-adv-heading25597_02146f-46\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading25597_02146f-46 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading25597_02146f-46[data-kb-block=\"kb-adv-heading25597_02146f-46\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading25597_02146f-46, .wp-block-kadence-advancedheading.kt-adv-heading25597_02146f-46[data-kb-block=\"kb-adv-heading25597_02146f-46\"]{font-size:25px;line-height:1;}}<\/style>\n<h1 class=\"kt-adv-heading25597_02146f-46 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading25597_02146f-46\">Angela Carrillo y Claudio Rivera: <br>Campeones Mundiales de Cueca en COFOCHILEX 2024<\/h1>\n\n\n\n<p>El <strong>Grupo Chile Berl\u00edn<\/strong> celebra un nuevo hito en su historia con la reciente coronaci\u00f3n de Angela Carrillo y Claudio Rivera como los Campeones Mundiales de Cueca en el Campeonato Mundial de Cueca <strong>COFOCHILEX<\/strong>, en su 21\u00aa versi\u00f3n. El certamen tuvo lugar del 14 al 20 de octubre de 2024 en la hist\u00f3rica ciudad de Pamplona, Espa\u00f1a, donde participaron representantes de 9 pa\u00edses, entre ellos Australia, Argentina, Estados Unidos, Canad\u00e1, Espa\u00f1a, Suiza, Reino Unido, Noruega y Alemania. <strong>Angela y Claudio<\/strong>, orgullosos representantes de Alemania, se alzaron con el primer lugar tras tres noches de intensas competencias.<br><br>El campeonato no solo fue una oportunidad para competir, sino tambi\u00e9n para compartir y aprender de grandes figuras del folclore chileno. Entre los invitados especiales estuvieron el grupo Alerzal de los R\u00edos, el Ballet Folkl\u00f3rico Nahuen y los campeones de cueca de Arica, Alejandra Ulloa y Victor Mu\u00f1oz, cuya presencia enriqueci\u00f3 el evento.<br> <br><strong>Claudio coment\u00f3 con entusiasmo: <br><\/strong><em>\u00abPara nosotros como competidores fue emocionante poder compartir con ellos, su talento y calidad humana signific\u00f3 mucho para nosotros\u00bb, destacando la importancia de este intercambio cultural.\u00bb<\/em><br><br>Una de las sorpresas m\u00e1s gratas para la pareja fue ser elegidos adem\u00e1s como Rey y Reina de su generaci\u00f3n por votaci\u00f3n de todos sus pares, un reconocimiento al carisma y camarader\u00eda que demostraron durante el evento. \u00abFue algo que no nos esper\u00e1bamos y que nos emocion\u00f3 bastante porque es un regalo que viene de tus propios compa\u00f1eros\u00bb, se\u00f1al\u00f3 Angela, al recordar este emotivo momento.<\/p>\n\n\n<style>.kb-row-layout-id25597_e632a5-16 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id25597_e632a5-16 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id25597_e632a5-16 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-sm, 1rem);row-gap:var(--global-kb-gap-md, 2rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id25597_e632a5-16 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id25597_e632a5-16 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id25597_e632a5-16 > .kt-row-column-wrap{row-gap:var(--global-kb-gap-sm, 1rem);padding-right:0px;padding-left:0px;grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id25597_e632a5-16 alignwide wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-row kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column25597_938eab-0c > .kt-inside-inner-col,.kadence-column25597_938eab-0c > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column25597_938eab-0c > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column25597_938eab-0c > .kt-inside-inner-col{flex-direction:column;}.kadence-column25597_938eab-0c > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column25597_938eab-0c > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column25597_938eab-0c{position:relative;}@media all and (max-width: 1024px){.kadence-column25597_938eab-0c > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column25597_938eab-0c > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column25597_938eab-0c\"><div class=\"kt-inside-inner-col\"><style>.kb-gallery-id-25597_30a9a0-fa.kb-gallery-ul.kb-gallery-type-fluidcarousel .kt-blocks-carousel figure .kb-gal-image-radius, .kb-gallery-id-25597_30a9a0-fa.kb-gallery-ul.kb-gallery-type-fluidcarousel .kt-blocks-carousel figure .kb-gal-image-radius img{height:300px;}.kb-gallery-id-25597_30a9a0-fa .kadence-blocks-gallery-item .kb-gal-image-radius, .kb-gallery-id-25597_30a9a0-fa .kb-slide-item .kb-gal-image-radius img{border-radius:0px 0px 0px 0px;;}.kb-gallery-wrap-id-25597_30a9a0-fa.wp-block-kadence-advancedgallery{overflow:visible;}.kb-gallery-wrap-id-25597_30a9a0-fa.wp-block-kadence-advancedgallery .kt-blocks-carousel{overflow:visible;max-width:100%;}@media all and (max-width: 767px){.kb-gallery-id-25597_30a9a0-fa.kb-gallery-ul.kb-gallery-type-fluidcarousel .kt-blocks-carousel figure .kb-gal-image-radius, .kb-gallery-id-25597_30a9a0-fa.kb-gallery-ul.kb-gallery-type-fluidcarousel .kt-blocks-carousel figure .kb-gal-image-radius img{height:150px;}}<\/style><div class=\"kb-gallery-wrap-id-25597_30a9a0-fa alignnone wp-block-kadence-advancedgallery\"><div class=\"kb-gallery-ul kb-gallery-non-static kb-gallery-type-fluidcarousel kb-gallery-id-25597_30a9a0-fa kb-gallery-caption-style-bottom-hover kb-gallery-filter-none\" data-image-filter=\"none\" data-lightbox-caption=\"true\"><div class=\"kt-blocks-carousel splide kt-carousel-container-dotstyle-dark kt-carousel-arrowstyle-whiteondark kt-carousel-dotstyle-dark kb-slider-group-arrow kb-slider-arrow-position-center\" data-slider-anim-speed=\"400\" data-slider-scroll=\"1\" data-slider-arrows=\"true\" data-slider-dots=\"true\" data-slider-hover-pause=\"false\" data-slider-auto=\"\" data-slider-speed=\"7000\" data-slider-type=\"fluidcarousel\" data-slider-center-mode=\"true\" data-slider-gap=\"10px\" data-slider-gap-tablet=\"10px\" data-slider-gap-mobile=\"10px\" data-show-pause-button=\"false\"><div class=\"splide__track\"><ul class=\"kt-blocks-carousel-init kb-blocks-fluid-carousel splide__list\"><li class=\"kb-slide-item kb-gallery-carousel-item splide__slide\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain\" ><img fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/grupochile.de\/wp-content\/uploads\/2024\/10\/angela-y-claudio-campeones-2014-scaled-e1730230068529-830x1024.jpeg\" width=\"830\" height=\"1024\" alt=\"angela-y-claudio-campeones-2024\" data-full-image=\"https:\/\/grupochile.de\/wp-content\/uploads\/2024\/10\/angela-y-claudio-campeones-2014-scaled-e1730230068529.jpeg\" data-light-image=\"https:\/\/grupochile.de\/wp-content\/uploads\/2024\/10\/angela-y-claudio-campeones-2014-scaled-e1730230068529.jpeg\" data-id=\"25602\" class=\"wp-image-25602 skip-lazy\" title=\"\" srcset=\"https:\/\/grupochile.de\/wp-content\/uploads\/2024\/10\/angela-y-claudio-campeones-2014-scaled-e1730230068529-830x1024.jpeg 830w, https:\/\/grupochile.de\/wp-content\/uploads\/2024\/10\/angela-y-claudio-campeones-2014-scaled-e1730230068529-243x300.jpeg 243w, https:\/\/grupochile.de\/wp-content\/uploads\/2024\/10\/angela-y-claudio-campeones-2014-scaled-e1730230068529-768x947.jpeg 768w, https:\/\/grupochile.de\/wp-content\/uploads\/2024\/10\/angela-y-claudio-campeones-2014-scaled-e1730230068529.jpeg 1143w\" sizes=\"(max-width: 830px) 100vw, 830px\" \/><\/div><\/div><\/figure><\/div><\/div><\/li><li class=\"kb-slide-item kb-gallery-carousel-item splide__slide\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain\" ><img decoding=\"async\" src=\"https:\/\/grupochile.de\/wp-content\/uploads\/2024\/10\/Campeones-coronacion.png\" width=\"991\" height=\"669\" alt=\"ang-cla-capmpeones\" data-full-image=\"https:\/\/grupochile.de\/wp-content\/uploads\/2024\/10\/Campeones-coronacion.png\" data-light-image=\"https:\/\/grupochile.de\/wp-content\/uploads\/2024\/10\/Campeones-coronacion.png\" data-id=\"25600\" class=\"wp-image-25600 skip-lazy\" title=\"\" srcset=\"https:\/\/grupochile.de\/wp-content\/uploads\/2024\/10\/Campeones-coronacion.png 991w, https:\/\/grupochile.de\/wp-content\/uploads\/2024\/10\/Campeones-coronacion-300x203.png 300w, https:\/\/grupochile.de\/wp-content\/uploads\/2024\/10\/Campeones-coronacion-768x518.png 768w\" sizes=\"(max-width: 991px) 100vw, 991px\" \/><\/div><\/div><\/figure><\/div><\/div><\/li><li class=\"kb-slide-item kb-gallery-carousel-item splide__slide\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain\" ><img decoding=\"async\" src=\"https:\/\/grupochile.de\/wp-content\/uploads\/2024\/10\/campeones-1024x869.jpeg\" width=\"1024\" height=\"869\" alt=\"campeones\" data-full-image=\"https:\/\/grupochile.de\/wp-content\/uploads\/2024\/10\/campeones.jpeg\" data-light-image=\"https:\/\/grupochile.de\/wp-content\/uploads\/2024\/10\/campeones.jpeg\" data-id=\"25603\" class=\"wp-image-25603 skip-lazy\" title=\"\" srcset=\"https:\/\/grupochile.de\/wp-content\/uploads\/2024\/10\/campeones-1024x869.jpeg 1024w, https:\/\/grupochile.de\/wp-content\/uploads\/2024\/10\/campeones-300x254.jpeg 300w, https:\/\/grupochile.de\/wp-content\/uploads\/2024\/10\/campeones-768x651.jpeg 768w, https:\/\/grupochile.de\/wp-content\/uploads\/2024\/10\/campeones.jpeg 1535w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><\/figure><\/div><\/div><\/li><li class=\"kb-slide-item kb-gallery-carousel-item splide__slide\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/grupochile.de\/wp-content\/uploads\/2024\/10\/angela-y-claudio-campeones-1-scaled-e1730229891412-673x1024.jpeg\" width=\"673\" height=\"1024\" alt=\"angela-y-claudio-campeones\" data-full-image=\"https:\/\/grupochile.de\/wp-content\/uploads\/2024\/10\/angela-y-claudio-campeones-1-scaled-e1730229891412.jpeg\" data-light-image=\"https:\/\/grupochile.de\/wp-content\/uploads\/2024\/10\/angela-y-claudio-campeones-1-scaled-e1730229891412.jpeg\" data-id=\"25601\" class=\"wp-image-25601 skip-lazy\" title=\"\" srcset=\"https:\/\/grupochile.de\/wp-content\/uploads\/2024\/10\/angela-y-claudio-campeones-1-scaled-e1730229891412-673x1024.jpeg 673w, https:\/\/grupochile.de\/wp-content\/uploads\/2024\/10\/angela-y-claudio-campeones-1-scaled-e1730229891412-197x300.jpeg 197w, https:\/\/grupochile.de\/wp-content\/uploads\/2024\/10\/angela-y-claudio-campeones-1-scaled-e1730229891412-768x1169.jpeg 768w, https:\/\/grupochile.de\/wp-content\/uploads\/2024\/10\/angela-y-claudio-campeones-1-scaled-e1730229891412-1009x1536.jpeg 1009w, https:\/\/grupochile.de\/wp-content\/uploads\/2024\/10\/angela-y-claudio-campeones-1-scaled-e1730229891412-1346x2048.jpeg 1346w, https:\/\/grupochile.de\/wp-content\/uploads\/2024\/10\/angela-y-claudio-campeones-1-scaled-e1730229891412.jpeg 1441w\" sizes=\"(max-width: 673px) 100vw, 673px\" \/><\/div><\/div><\/figure><\/div><\/div><\/li><li class=\"kb-slide-item kb-gallery-carousel-item splide__slide\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/grupochile.de\/wp-content\/uploads\/2024\/10\/COFOCHILEX-2024-1024x577.jpeg\" width=\"1024\" height=\"577\" alt=\"COFOCHILEX-2024\" data-full-image=\"https:\/\/grupochile.de\/wp-content\/uploads\/2024\/10\/COFOCHILEX-2024.jpeg\" data-light-image=\"https:\/\/grupochile.de\/wp-content\/uploads\/2024\/10\/COFOCHILEX-2024.jpeg\" data-id=\"25604\" class=\"wp-image-25604 skip-lazy\" title=\"\" srcset=\"https:\/\/grupochile.de\/wp-content\/uploads\/2024\/10\/COFOCHILEX-2024-1024x577.jpeg 1024w, https:\/\/grupochile.de\/wp-content\/uploads\/2024\/10\/COFOCHILEX-2024-300x169.jpeg 300w, https:\/\/grupochile.de\/wp-content\/uploads\/2024\/10\/COFOCHILEX-2024-768x432.jpeg 768w, https:\/\/grupochile.de\/wp-content\/uploads\/2024\/10\/COFOCHILEX-2024-1536x865.jpeg 1536w, https:\/\/grupochile.de\/wp-content\/uploads\/2024\/10\/COFOCHILEX-2024.jpeg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><\/figure><\/div><\/div><\/li><li class=\"kb-slide-item kb-gallery-carousel-item splide__slide\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/grupochile.de\/wp-content\/uploads\/2024\/10\/COFOCHILEX-2024-campeones-1024x577.jpeg\" width=\"1024\" height=\"577\" alt=\"COFOCHILEX-2024-campeones\" data-full-image=\"https:\/\/grupochile.de\/wp-content\/uploads\/2024\/10\/COFOCHILEX-2024-campeones.jpeg\" data-light-image=\"https:\/\/grupochile.de\/wp-content\/uploads\/2024\/10\/COFOCHILEX-2024-campeones.jpeg\" data-id=\"25605\" class=\"wp-image-25605 skip-lazy\" title=\"\" srcset=\"https:\/\/grupochile.de\/wp-content\/uploads\/2024\/10\/COFOCHILEX-2024-campeones-1024x577.jpeg 1024w, https:\/\/grupochile.de\/wp-content\/uploads\/2024\/10\/COFOCHILEX-2024-campeones-300x169.jpeg 300w, https:\/\/grupochile.de\/wp-content\/uploads\/2024\/10\/COFOCHILEX-2024-campeones-768x432.jpeg 768w, https:\/\/grupochile.de\/wp-content\/uploads\/2024\/10\/COFOCHILEX-2024-campeones-1536x865.jpeg 1536w, https:\/\/grupochile.de\/wp-content\/uploads\/2024\/10\/COFOCHILEX-2024-campeones.jpeg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><\/figure><\/div><\/div><\/li><\/ul><\/div><\/div><\/div><\/div><\/div><\/div>\n\n\n<style>.kadence-column25597_71d81d-58 > .kt-inside-inner-col,.kadence-column25597_71d81d-58 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column25597_71d81d-58 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column25597_71d81d-58 > .kt-inside-inner-col{flex-direction:column;}.kadence-column25597_71d81d-58 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column25597_71d81d-58 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column25597_71d81d-58{position:relative;}@media all and (max-width: 1024px){.kadence-column25597_71d81d-58 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column25597_71d81d-58 > .kt-inside-inner-col{padding-right:var(--global-kb-spacing-xs, 1rem);padding-left:var(--global-kb-spacing-xs, 1rem);flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column25597_71d81d-58\"><div class=\"kt-inside-inner-col\">\n<p>El triunfo no solo marca un logro personal para la pareja, sino tambi\u00e9n para el Grupo Chile Berl\u00edn, ya que ambos pertenecen a esta comunidad folcl\u00f3rica que promueve la cultura chilena en Alemania. Lo que hace a\u00fan m\u00e1s especial este campeonato es que los campeones salientes, M\u00f3nica y Osvaldo, tambi\u00e9n miembros y fundadores del Grupo Chile Berl\u00edn, hicieron entrega del t\u00edtulo a sus compa\u00f1eros de grupo, consolidando as\u00ed la presencia de la agrupaci\u00f3n en la \u00e9lite del folclore mundial.<br><br>Como parte de su premio, <strong>Claudio y Angela<\/strong> recibieron una invitaci\u00f3n para participar en el Campeonato de <strong>Arica 2025<\/strong>, adem\u00e1s de una ruana y un chamanto de \u00abChamantos Lo Abarca\u00bb. Para ellos, la experiencia fue una combinaci\u00f3n de competencia, tradici\u00f3n y el fortalecimiento de lazos con su generaci\u00f3n, a quienes llaman cari\u00f1osamente \u00abLos Sinde\u00bb.<br><br>El Grupo Chile Berl\u00edn no solo celebra el \u00e9xito de sus campeones actuales, sino tambi\u00e9n la continuidad de su legado en el mundo de la cueca, y seguir\u00e1 apoyando y difundiendo el folclore chileno en Alemania y m\u00e1s all\u00e1.<\/p>\n<\/div><\/div>\n\n<\/div><\/div>\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Angela Carrillo und Claudio Rivera wurden bei der 21. Auflage der Weltmeisterschaft der Cueca,<\/p>","protected":false},"author":1,"featured_media":25606,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"right","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"default","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"categories":[33],"tags":[57,56,58],"class_list":["post-25597","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-33","tag-campeones","tag-cueca","tag-espana"],"_links":{"self":[{"href":"https:\/\/grupochile.de\/de\/wp-json\/wp\/v2\/posts\/25597","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/grupochile.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/grupochile.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/grupochile.de\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/grupochile.de\/de\/wp-json\/wp\/v2\/comments?post=25597"}],"version-history":[{"count":22,"href":"https:\/\/grupochile.de\/de\/wp-json\/wp\/v2\/posts\/25597\/revisions"}],"predecessor-version":[{"id":27913,"href":"https:\/\/grupochile.de\/de\/wp-json\/wp\/v2\/posts\/25597\/revisions\/27913"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/grupochile.de\/de\/wp-json\/wp\/v2\/media\/25606"}],"wp:attachment":[{"href":"https:\/\/grupochile.de\/de\/wp-json\/wp\/v2\/media?parent=25597"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/grupochile.de\/de\/wp-json\/wp\/v2\/categories?post=25597"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/grupochile.de\/de\/wp-json\/wp\/v2\/tags?post=25597"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}